{"id":3287,"date":"2019-10-17T16:02:25","date_gmt":"2019-10-17T08:02:25","guid":{"rendered":"https:\/\/taizyfoodmachines.com\/?p=3287"},"modified":"2019-10-17T16:02:25","modified_gmt":"2019-10-17T08:02:25","slug":"current-status-and-future-development-trend-of-cassava-industry","status":"publish","type":"post","link":"https:\/\/taizyfoodmachines.com\/pt\/current-status-and-future-development-trend-of-cassava-industry\/","title":{"rendered":"Situa\u00e7\u00e3o atual e tend\u00eancia futura de desenvolvimento da ind\u00fastria da mandioca"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;3287&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;9&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.6&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.6\\\/5 - (9 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Current status and future development trend of cassava industry&quot;,&quot;width&quot;:&quot;130.9&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 130.9px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4,6\/5 - (9 votos)    <\/div>     <\/div> <p>A ind\u00fastria de processamento de mandioca abrange uma ampla gama de ind\u00fastrias, incluindo a ind\u00fastria de plantio de mandioca, o amido e as ind\u00fastrias de processamento de \u00e1lcool. O mercado real e o mercado potencial s\u00e3o enormes em v\u00e1rios dom\u00ednios que envolvem a economia nacional, a subsist\u00eancia e a vida das pessoas. E tem perspectivas de desenvolvimento extremamente amplas.<\/p> <h2>Status da ind\u00fastria de plantio de mandioca:<\/h2> <p>Actualmente, existem quase 70 pa\u00edses que plantam mandioca. Segundo as estat\u00edsticas, a \u00e1rea mundial de planta\u00e7\u00e3o de mandioca \u00e9 de cerca de 16,58 milh\u00f5es de hectares, a produ\u00e7\u00e3o total de batata fresca \u00e9 de cerca de 166 milh\u00f5es de toneladas e o rendimento m\u00e9dio de batata fresca \u00e9 de 10,14 toneladas\/ha. O pa\u00eds com a maior \u00e1rea de plantio de mandioca do mundo \u00e9 a Nig\u00e9ria, com 3,5 milh\u00f5es de hectares. Seguido pelo Congo (RDC), Brasil, Indon\u00e9sia e Tail\u00e2ndia. A \u00e1rea de plantio de mandioca na China representa cerca de 1,5% da \u00e1rea total de plantio do mundo.<\/p> <figure id=\"attachment_3290\" aria-describedby=\"caption-attachment-3290\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3290\" src=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava.jpg\" alt=\"Garri feito de mandioca\" width=\"640\" height=\"480\" title=\"\" srcset=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava.jpg 640w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava-300x225.jpg 300w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava-414x310.jpg 414w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava-74x55.jpg 74w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava-111x83.jpg 111w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-made-by-cassava-215x161.jpg 215w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-3290\" class=\"wp-caption-text\">Garri feito de mandioca<\/figcaption><\/figure> <p>Atualmente, a mandioca \u00e9 usada principalmente para fazer amido, amido modificado e \u00e1lcool. Hoje, discutimos principalmente as perspectivas de produ\u00e7\u00e3o e processamento do p\u00f3 Garri.<\/p> <p class=\"translation-block\">O fluxo de trabalho principal da <a href=\"https:\/\/taizyfoodmachines.com\/pt\/garri-production-line-cassava-flour-production-line\/\">linha de produ\u00e7\u00e3o de Garri<\/a> inclui: lavagem e descascamento \u2013 triturar \u2013 prensar a desidratar \u2013 fermenta\u00e7\u00e3o \u2013 triturar \u2013 fritar - peneirar \u2013 quebrar novamente.<\/p> <figure id=\"attachment_3291\" aria-describedby=\"caption-attachment-3291\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3291\" src=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line.jpg\" alt=\"linha de produ\u00e7\u00e3o garri\" width=\"1200\" height=\"520\" title=\"\" srcset=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line.jpg 1200w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line-300x130.jpg 300w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line-768x333.jpg 768w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line-1024x444.jpg 1024w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/garri-production-line-990x429.jpg 990w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-3291\" class=\"wp-caption-text\">Linha de Produ\u00e7\u00e3o Garri<\/figcaption><\/figure> <p>A limpeza e o descascamento s\u00e3o utilizados principalmente para remover sedimentos e a epiderme da mandioca. Estudos t\u00eam demonstrado que o teor de \u00e1cido cian\u00eddrico na epiderme da mandioca \u00e9 o mais elevado, e o \u00e1cido cian\u00eddrico pode causar asfixia e morte celular, causando danos extremamente graves ao corpo humano. Portanto, a casca da mandioca deve ser totalmente removida, e a taxa de descascamento desta m\u00e1quina pode chegar a 98%.<\/p> <p>A fermenta\u00e7\u00e3o produz principalmente o sabor \u00e1cido e, no processo de fermenta\u00e7\u00e3o, um grande n\u00famero de bact\u00e9rias ativas ser\u00e1 produzido, e prote\u00ednas, amino\u00e1cidos e similares ser\u00e3o mais ben\u00e9ficos para o corpo humano absorver e ter\u00e3o grandes vantagens para aumentar a imunidade e preven\u00e7\u00e3o de doen\u00e7as.<\/p> <figure id=\"attachment_3292\" aria-describedby=\"caption-attachment-3292\" style=\"width: 892px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3292 size-full\" src=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/cassava.jpg\" alt=\"processamento de mandioca\" width=\"892\" height=\"544\" title=\"\" srcset=\"https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/cassava.jpg 892w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/cassava-300x183.jpg 300w, https:\/\/taizyfoodmachines.com\/wp-content\/uploads\/2019\/10\/cassava-768x468.jpg 768w\" sizes=\"auto, (max-width: 892px) 100vw, 892px\" \/><figcaption id=\"caption-attachment-3292\" class=\"wp-caption-text\">Processamento de Mandioca<\/figcaption><\/figure> <h2>A tend\u00eancia atual de desenvolvimento da tecnologia de processamento de mandioca \u00e9:<\/h2> <ol> <li>Preste aten\u00e7\u00e3o ao cultivo de variedades de alto rendimento e alto teor de amido.<\/li> <li>Da gest\u00e3o extensiva \u00e0 gest\u00e3o intensiva.<\/li> <\/ol>","protected":false},"excerpt":{"rendered":"<p>The cassava processing industry covers a wide range of industries, including the cassava planting industry, the starch, and the alcohol processing industries. The real market and the potential market are huge in various fields involving the national economy, people&#8217;s livelihood, and people&#8217;s lives. And it has extremely broad development prospects. Cassava planting industry status\uff1a At [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-3287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"views":2,"_links":{"self":[{"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/posts\/3287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/comments?post=3287"}],"version-history":[{"count":0,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/posts\/3287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/media\/3289"}],"wp:attachment":[{"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/media?parent=3287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/categories?post=3287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taizyfoodmachines.com\/pt\/wp-json\/wp\/v2\/tags?post=3287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}